{"id":633319,"date":"2023-02-02T16:30:21","date_gmt":"2023-02-02T15:30:21","guid":{"rendered":"https:\/\/innovalia-metrology.cbtpruebas.es\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/"},"modified":"2023-03-13T13:43:39","modified_gmt":"2023-03-13T12:43:39","slug":"inno-fix-roller-shelf","status":"publish","type":"page","link":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/","title":{"rendered":"INNO-FIX ROLLER SHELF"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_margin=&#8221;1em||1em||true|false&#8221; custom_padding=&#8221;0px||0px|1em|true|false&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; header_3_font_size=&#8221;25px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>INNO-FIX ROLLER SHELF<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2023\/02\/rolloer.webp&#8221; alt=&#8221;INNO-FIX KIT M&#8221; title_text=&#8221;rolloer&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|1em|||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;630674,630662&#8243; posts_number=&#8221;24&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; custom_css_gallery_item=&#8221;width: 20% !important;||margin: 0 !important;||display: block;||margin-left: auto;||margin-right: auto;||&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#f7f7f7&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>\u4f7f\u7528\u65b9\u6cd5<\/h3>\n<p>[\/et_pb_text][et_pb_video src_webm=&#8221;https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2020\/09\/spark-op2.mp4&#8243; _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_code _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9000-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"9000\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ja\/wp-json\/wp\/v2\/pages\/633319#wpcf7-f9000-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9000\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9000-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:9000,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;,&quot;notice_dismissed_update-cf7-5.4&quot;:true,&quot;notice_dismissed_rollback-cf7-5.4.1&quot;:true}}\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label><\/label>\n<\/p>\n<h4>\u30ab\u30bf\u30ed\u30b0\u8acb\u6c42\u306f\u3053\u3061\u3089\u3078\n<\/h4>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"name-560\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name*\" value=\"\" type=\"text\" name=\"name-560\" \/><\/span><\/label><br \/>\n<label><span class=\"wpcf7-form-control-wrap\" data-name=\"empresa-560\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company*\" value=\"\" type=\"text\" name=\"empresa-560\" \/><\/span><\/label><br \/>\n<label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E\u30e1\u30fc\u30eb\u30a2\u30c9\u30ec\u30b9*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label><br \/>\n<span class=\"wpcf7-form-control-wrap title\" data-name=\"title\"><input type=\"hidden\" name=\"title\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"INNO-FIX ROLLER SHELF\"><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" id=\"btn_pedir-jp\" type=\"submit\" value=\"\u9001\u4fe1\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"152\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>INNO-FIX ROLLER SHELF\u4f7f\u7528\u65b9\u6cd5<p class=\"wpcf7-contact-form-not-found\"><strong>\u30a8\u30e9\u30fc:<\/strong> \u30b3\u30f3\u30bf\u30af\u30c8\u30d5\u30a9\u30fc\u30e0\u304c\u898b\u3064\u304b\u308a\u307e\u305b\u3093\u3002<\/p><\/p>\n","protected":false},"author":85986,"featured_media":0,"parent":632461,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-633319","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS\" \/>\n<meta property=\"og:description\" content=\"INNO-FIX ROLLER SHELF\u4f7f\u7528\u65b9\u6cd5\" \/>\n<meta property=\"og:url\" content=\"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/\" \/>\n<meta property=\"og:site_name\" content=\"INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-13T12:43:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2025\/10\/logo-innovalia-metrology.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/accessories\\\/%e6%b2%bb%e5%85%b7\\\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\\\/inno-fix-roller-shelf\\\/\",\"url\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/accessories\\\/%e6%b2%bb%e5%85%b7\\\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\\\/inno-fix-roller-shelf\\\/\",\"name\":\"INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#website\"},\"datePublished\":\"2023-02-02T15:30:21+00:00\",\"dateModified\":\"2023-03-13T12:43:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/accessories\\\/%e6%b2%bb%e5%85%b7\\\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\\\/inno-fix-roller-shelf\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/accessories\\\/%e6%b2%bb%e5%85%b7\\\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\\\/inno-fix-roller-shelf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/accessories\\\/%e6%b2%bb%e5%85%b7\\\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\\\/inno-fix-roller-shelf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u88fd \u54c1\",\"item\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/%e8%a3%bd-%e5%93%81\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u691c\u8a3c\u30fb\u6821\u6b63\u30b7\u30b9\u30c6\u30e0\",\"item\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/metrology-products\\\/accessories\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u6cbb\u5177\",\"item\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/metrology-products\\\/accessories\\\/fixtures\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u642c\u9001\u6cbb\u5177\",\"item\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/metrology-products\\\/accessories\\\/fixtures\\\/palletizing-systems\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"INNO-FIX ROLLER SHELF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/\",\"name\":\"INNOVALIA METROLOGY\",\"description\":\"METROLOGY SOLUTIONS\",\"publisher\":{\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#organization\",\"name\":\"INNOVALIA METROLOGY\",\"url\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/innovalia-metrology.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Diseno-sin-titulo-36.png\",\"contentUrl\":\"https:\\\/\\\/innovalia-metrology.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Diseno-sin-titulo-36.png\",\"width\":300,\"height\":250,\"caption\":\"INNOVALIA METROLOGY\"},\"image\":{\"@id\":\"https:\\\/\\\/innovalia-metrology.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/IMetrology_ES\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/innovalia-metrology\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCV7L_atMrcg6DUslHYeDaYQ\"]}]}<\/script>","yoast_head_json":{"title":"INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/","og_locale":"ja_JP","og_type":"article","og_title":"INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS","og_description":"INNO-FIX ROLLER SHELF\u4f7f\u7528\u65b9\u6cd5","og_url":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/","og_site_name":"INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS","article_modified_time":"2023-03-13T12:43:39+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2025\/10\/logo-innovalia-metrology.png","type":"image\/png"}],"twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"2\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/","url":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/","name":"INNO-FIX ROLLER SHELF | INNOVALIA METROLOGY | INDUSTRIAL METROLOGY SOLUTIONS","isPartOf":{"@id":"https:\/\/innovalia-metrology.com\/ja\/#website"},"datePublished":"2023-02-02T15:30:21+00:00","dateModified":"2023-03-13T12:43:39+00:00","breadcrumb":{"@id":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/accessories\/%e6%b2%bb%e5%85%b7\/%e6%90%ac%e9%80%81%e6%b2%bb%e5%85%b7\/inno-fix-roller-shelf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/innovalia-metrology.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u88fd \u54c1","item":"https:\/\/innovalia-metrology.com\/ja\/%e8%a3%bd-%e5%93%81\/"},{"@type":"ListItem","position":3,"name":"\u691c\u8a3c\u30fb\u6821\u6b63\u30b7\u30b9\u30c6\u30e0","item":"https:\/\/innovalia-metrology.com\/ja\/metrology-products\/accessories\/"},{"@type":"ListItem","position":4,"name":"\u6cbb\u5177","item":"https:\/\/innovalia-metrology.com\/ja\/metrology-products\/accessories\/fixtures\/"},{"@type":"ListItem","position":5,"name":"\u642c\u9001\u6cbb\u5177","item":"https:\/\/innovalia-metrology.com\/ja\/metrology-products\/accessories\/fixtures\/palletizing-systems\/"},{"@type":"ListItem","position":6,"name":"INNO-FIX ROLLER SHELF"}]},{"@type":"WebSite","@id":"https:\/\/innovalia-metrology.com\/ja\/#website","url":"https:\/\/innovalia-metrology.com\/ja\/","name":"INNOVALIA METROLOGY","description":"METROLOGY SOLUTIONS","publisher":{"@id":"https:\/\/innovalia-metrology.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/innovalia-metrology.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/innovalia-metrology.com\/ja\/#organization","name":"INNOVALIA METROLOGY","url":"https:\/\/innovalia-metrology.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/innovalia-metrology.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2025\/10\/Diseno-sin-titulo-36.png","contentUrl":"https:\/\/innovalia-metrology.com\/wp-content\/uploads\/2025\/10\/Diseno-sin-titulo-36.png","width":300,"height":250,"caption":"INNOVALIA METROLOGY"},"image":{"@id":"https:\/\/innovalia-metrology.com\/ja\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/IMetrology_ES","https:\/\/www.linkedin.com\/company\/innovalia-metrology","https:\/\/www.youtube.com\/channel\/UCV7L_atMrcg6DUslHYeDaYQ"]}]}},"_links":{"self":[{"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/pages\/633319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/users\/85986"}],"replies":[{"embeddable":true,"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/comments?post=633319"}],"version-history":[{"count":3,"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/pages\/633319\/revisions"}],"predecessor-version":[{"id":633349,"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/pages\/633319\/revisions\/633349"}],"up":[{"embeddable":true,"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/pages\/632461"}],"wp:attachment":[{"href":"https:\/\/innovalia-metrology.com\/ja\/wp-json\/wp\/v2\/media?parent=633319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}